{"id":1435,"date":"2020-05-05T17:49:01","date_gmt":"2020-05-05T20:49:01","guid":{"rendered":"https:\/\/plkc.com.br\/?p=1435"},"modified":"2020-10-29T17:50:15","modified_gmt":"2020-10-29T20:50:15","slug":"validade-dos-contratos-eletronicos","status":"publish","type":"post","link":"https:\/\/plkc.com.br\/en\/validade-dos-contratos-eletronicos\/","title":{"rendered":"Validade dos Contratos Eletr\u00f4nicos"},"content":{"rendered":"<p>O isolamento social imposto pela COVID-19 incrementou a utiliza\u00e7\u00e3o dos meios virtuais de comunica\u00e7\u00e3o e, por consequ\u00eancia, acelerou a implementa\u00e7\u00e3o destes meios para a realiza\u00e7\u00e3o de neg\u00f3cios, os quais tamb\u00e9m podem ser formalizados de forma digital, sem o encontro presencial das partes contratantes.<\/p>\n\n\n\n<p>Essa forma de contrata\u00e7\u00e3o n\u00e3o \u00e9 nova. Diariamente compramos bens e servi\u00e7os por meio de clicks em sites de fornecedores, cujos produtos s\u00e3o entregues posteriormente e, em diversos casos, de forma instant\u00e2nea, pela pr\u00f3pria rede mundial de computadores (livros digitais, cursos on-line, cr\u00e9dito, etc).<\/p>\n\n\n\n<p>O Brasil instituiu, em 2001, a Infraestrutura de Chaves P\u00fablicas Brasileira \u2013 ICP-Brasil, objetivando garantir a autenticidade, a integridade e a validade jur\u00eddica dos contratos em forma eletr\u00f4nica.<\/p>\n\n\n\n<p>&nbsp;Em mar\u00e7o desse ano, aperfei\u00e7oando o sistema e a nova tend\u00eancia, o Presidente editou decreto que estabelece a forma e os requisitos para a digitaliza\u00e7\u00e3o de documentos p\u00fablicos e privados, dotando-os dos mesmos efeitos legais dos documentos em papel.<\/p>\n\n\n\n<p>O Conselho Nacional de Justi\u00e7a tamb\u00e9m editou normas, v\u00e1lidas enquanto perdurar a pandemia, permitindo sejam lavradas escrituras p\u00fablicas de forma digital, bem como sejam elas levadas a registro de forma n\u00e3o-presencial.<\/p>\n\n\n\n<p>Em suma, o futuro chegou e estamos vivendo uma nova realidade, na qual a forma simples e digital de se formalizar os contratos se tornar\u00e1 a regra, inclusive com o seu aprimoramento para abranger, tamb\u00e9m, os contratos solenes, tais como escrituras p\u00fablicas, testamento e outros, n\u00e3o s\u00f3 com o objetivo de aplacar os efeitos da pandemia nos neg\u00f3cios mas, tamb\u00e9m e principalmente, para nortear a forma pela qual passar\u00e3o a ser feitas todas as negocia\u00e7\u00f5es e contrata\u00e7\u00f5es, ap\u00f3s vencida a quest\u00e3o de sa\u00fade.<\/p>\n\n\n\n<p>H\u00e1, evidentemente, requisitos que devem ser respeitados em cada tipo de contrato e nosso escrit\u00f3rio est\u00e1 preparado a orientar nossos clientes a formalizar os seus neg\u00f3cios digitalmente e de forma segura.<\/p>","protected":false},"excerpt":{"rendered":"<p>O isolamento social imposto pela COVID-19 incrementou a utiliza\u00e7\u00e3o dos meios virtuais de comunica\u00e7\u00e3o e, por consequ\u00eancia, acelerou a implementa\u00e7\u00e3o destes meios para a realiza\u00e7\u00e3o de neg\u00f3cios, os quais tamb\u00e9m podem ser formalizados de forma digital, sem o encontro presencial das partes contratantes. Essa forma de contrata\u00e7\u00e3o n\u00e3o \u00e9 nova. Diariamente compramos bens e servi\u00e7os [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[27],"tags":[],"class_list":["post-1435","post","type-post","status-publish","format-standard","hentry","category-boletim-civel"],"_links":{"self":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/1435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/comments?post=1435"}],"version-history":[{"count":0,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/1435\/revisions"}],"wp:attachment":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/media?parent=1435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/categories?post=1435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/tags?post=1435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}