{"id":2562,"date":"2022-03-07T15:10:00","date_gmt":"2022-03-07T18:10:00","guid":{"rendered":"https:\/\/plkc.com.br\/?p=2562"},"modified":"2022-03-07T15:10:10","modified_gmt":"2022-03-07T18:10:10","slug":"prazo-para-atualizacao-anual-de-informacoes-no-rde-ied","status":"publish","type":"post","link":"https:\/\/plkc.com.br\/en\/prazo-para-atualizacao-anual-de-informacoes-no-rde-ied\/","title":{"rendered":"Prazo para atualiza\u00e7\u00e3o anual de informa\u00e7\u00f5es no Registro de Investimento Estrangeiro Direto (RDE-IED) perante O Banco Central Do Brasil &#8211; BACEN"},"content":{"rendered":"<p>As empresas registradas no sistema do <a href=\"https:\/\/www.bcb.gov.br\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.bcb.gov.br\/\" rel=\"noreferrer noopener\">Banco Central do Brasil \u2013 BACEN<\/a> (\u201cBanco Central\u201d) que possuam s\u00f3cio n\u00e3o residente ou com sede no exterior dever\u00e3o atualizar suas informa\u00e7\u00f5es referentes aos <a href=\"https:\/\/plkc.com.br\/en\/declaracao-de-capitais-brasileiros-no-exterio\/\" data-type=\"URL\" data-id=\"https:\/\/plkc.com.br\/declaracao-de-capitais-brasileiros-no-exterio\/\">valores de ativo<\/a>, patrim\u00f4nio l\u00edquido e capital social integralizado at\u00e9 o dia 31.03.2022.<\/p>\n\n\n\n<p>A atualiza\u00e7\u00e3o anual das informa\u00e7\u00f5es deve ser realizada por meio do <a href=\"https:\/\/www.bcb.gov.br\/estabilidadefinanceira\/registrocapitaisestrangeiros\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.bcb.gov.br\/estabilidadefinanceira\/registrocapitaisestrangeiros\" rel=\"noreferrer noopener\">Sistema de Registro de Investimento Estrangeiro Direto (RDE-IED)<\/a> do Banco Central, at\u00e9 31 de mar\u00e7o de cada ano, com base em 31 de dezembro do ano anterior (Circular BACEN n\u00ba 3.814\/2016, alterada pela Circular BACEN n\u00ba 3.822\/2017).<\/p>\n\n\n\n<p>Para as empresas receptoras de investimento estrangeiro direto com patrim\u00f4nio l\u00edquido ou ativo superiores a R$ 250.000.000,00 \u00e9 obrigat\u00f3rio o preenchimento da Declara\u00e7\u00e3o Econ\u00f4mico-Financeira trimestralmente, nos prazos abaixo:<\/p>\n\n\n\n<p><strong>a)&nbsp;<\/strong>at\u00e9 31 de mar\u00e7o, referente \u00e0 data-base de 31 de dezembro do ano anterior;<\/p>\n\n\n\n<p><strong>b)&nbsp;<\/strong>at\u00e9 30 de junho, referente \u00e0 data-base de 31 de mar\u00e7o;<\/p>\n\n\n\n<p><strong>c)<\/strong>&nbsp;at\u00e9 30 de setembro, referente \u00e0 data-base de 30 de junho; e<\/p>\n\n\n\n<p><strong>d)<\/strong>&nbsp;at\u00e9 31 de dezembro, referente \u00e0 data-base de 30 de setembro.<\/p>\n\n\n\n<p>As empresas que deixarem de prestar as informa\u00e7\u00f5es ou prestarem informa\u00e7\u00f5es incorretas ou falsas estar\u00e3o sujeitas \u00e0 multa a ser aplicada pelo Banco Central.<\/p>\n\n\n\n<p>Nosso Escrit\u00f3rio permanece \u00e0 disposi\u00e7\u00e3o para esclarecer quaisquer d\u00favidas relativas \u00e0 atualiza\u00e7\u00e3o das informa\u00e7\u00f5es perante o Banco Central.<\/p>","protected":false},"excerpt":{"rendered":"<p>As empresas registradas no sistema do Banco Central do Brasil \u2013 BACEN (\u201cBanco Central\u201d) que possuam s\u00f3cio n\u00e3o residente ou com sede no exterior dever\u00e3o atualizar suas informa\u00e7\u00f5es referentes aos valores de ativo, patrim\u00f4nio l\u00edquido e capital social integralizado at\u00e9 o dia 31.03.2022. A atualiza\u00e7\u00e3o anual das informa\u00e7\u00f5es deve ser realizada por meio do Sistema [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[7],"tags":[99,35,97,98],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletim-societario","tag-banco-central","tag-bens-no-exterior","tag-rde-ied","tag-investimento"],"_links":{"self":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":0,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/media\/2564"}],"wp:attachment":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}