{"id":2931,"date":"2025-12-15T15:20:00","date_gmt":"2025-12-15T18:20:00","guid":{"rendered":"https:\/\/plkc.com.br\/?p=2931"},"modified":"2026-01-05T15:22:02","modified_gmt":"2026-01-05T18:22:02","slug":"ibs-cbs-contratos-de-locacao-nao-residencial","status":"publish","type":"post","link":"https:\/\/plkc.com.br\/en\/ibs-cbs-contratos-de-locacao-nao-residencial\/","title":{"rendered":"IBS \/ CBS \u2013 Contratos de Loca\u00e7\u00e3o N\u00e3o Residencial"},"content":{"rendered":"<p>Relembramos que os contratos de loca\u00e7\u00e3o de im\u00f3veis n\u00e3o residenciais podem manter a sua atual carga tribut\u00e1ria no que diz respeito aos tributos indiretos (PIS e Cofins) pelos prazos de dura\u00e7\u00e3o dos correspondentes contratos, desde que (a) tenham sido assinados at\u00e9 a data de in\u00edcio de vig\u00eancia da Lei Complementar 214, 16 de janeiro de 2025, mediante comprova\u00e7\u00e3o por assinatura eletr\u00f4nica ou firma reconhecida, e (b) sejam levados a registro em Cart\u00f3rio de Registro de Im\u00f3veis ou de Registro de T\u00edtulos e Documentos at\u00e9 31 de dezembro de 2025, ou que sejam disponibilizados para a Receita Federal do Brasil e para o Comit\u00ea Gestor do Imposto sobre Bens e Servi\u00e7os, nos termos de regulamento ainda a ser publicado (artigo 487, \u00a7 1\u00ba, da Lei Complementar 214\/2025).<\/p>\n\n\n\n<p>Para se ter o referido tratamento em rela\u00e7\u00e3o aos contratos de loca\u00e7\u00e3o de im\u00f3veis residenciais, basta a comprova\u00e7\u00e3o de que tenham sido assinados at\u00e9 a data de in\u00edcio de vig\u00eancia da Lei Complementar 214, mediante comprova\u00e7\u00e3o por assinatura eletr\u00f4nica, firma reconhecida ou pagamento no m\u00eas seguinte ao do 1\u00ba aluguel.<\/p>\n\n\n\n<p>Nesse sentido, caso tenha interesse em manter a tributa\u00e7\u00e3o atual, recomenda-se que os contratos de loca\u00e7\u00e3o n\u00e3o residencial vigentes, cuja assinatura possa comprovadamente ser demonstrada como sendo anterior \u00e0 vig\u00eancia da Lei Complementar, sejam levados a registro antes do t\u00e9rmino deste ano de 2025.<\/p>\n\n\n\n<p>Os nossos profissionais ficam \u00e0 disposi\u00e7\u00e3o para auxili\u00e1-los nos que seja necess\u00e1rio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Relembramos que os contratos de loca\u00e7\u00e3o de im\u00f3veis n\u00e3o residenciais podem manter a sua atual carga tribut\u00e1ria no que diz respeito aos tributos indiretos (PIS e Cofins) pelos prazos de dura\u00e7\u00e3o dos correspondentes contratos.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"class_list":["post-2931","post","type-post","status-publish","format-standard","hentry","category-boletim-tributario"],"_links":{"self":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":1,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/2931\/revisions"}],"predecessor-version":[{"id":2932,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/posts\/2931\/revisions\/2932"}],"wp:attachment":[{"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/categories?post=2931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plkc.com.br\/en\/wp-json\/wp\/v2\/tags?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}